{"id":11291,"date":"2020-11-25T09:50:32","date_gmt":"2020-11-25T09:50:32","guid":{"rendered":"https:\/\/www.ctp.eu\/?page_id=11291"},"modified":"2023-11-02T13:58:33","modified_gmt":"2023-11-02T11:58:33","slug":"community","status":"publish","type":"page","link":"https:\/\/ctp.rvltpreview.com\/sk\/portfolio\/mixed-use\/community\/","title":{"rendered":"Kancel\u00e1rska komunita"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":67,"featured_media":0,"parent":72,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"templates\/urban-parks.php","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-11291","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<title>Office Community - Commercial Real Estate Developer And Manager<\/title>\n<meta name=\"description\" content=\"We have been supporting the education of young talents for a long time, and within CTParks we also support community growth.\" \/>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"sk_SK\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Office Community\" \/>\n<meta property=\"og:description\" content=\"We have been supporting the education of young talents for a long time, and within CTParks we also support community growth.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ctp.rvltpreview.com\/sk\/portfolio\/mixed-use\/community\/\" \/>\n<meta property=\"og:site_name\" content=\"Commercial Real Estate Developer And Manager\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-02T11:58:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ctp.rvltpreview.com\/wp-content\/uploads\/2020\/12\/ctp-community-web.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"3000\" \/>\n\t<meta property=\"og:image:height\" content=\"1246\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ctp.rvltpreview.com\\\/portfolio\\\/mixed-use\\\/community\\\/\",\"url\":\"https:\\\/\\\/ctp.rvltpreview.com\\\/portfolio\\\/mixed-use\\\/community\\\/\",\"name\":\"Office Community - Commercial Real Estate Developer And Manager\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ctp.rvltpreview.com\\\/#website\"},\"datePublished\":\"2020-11-25T09:50:32+00:00\",\"dateModified\":\"2023-11-02T11:58:33+00:00\",\"description\":\"We have been supporting the education of young talents for a long time, and within CTParks we also support community growth.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ctp.rvltpreview.com\\\/portfolio\\\/mixed-use\\\/community\\\/#breadcrumb\"},\"inLanguage\":\"sk-SK\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ctp.rvltpreview.com\\\/portfolio\\\/mixed-use\\\/community\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ctp.rvltpreview.com\\\/portfolio\\\/mixed-use\\\/community\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ctp.rvltpreview.com\\\/cs\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Portfolio\",\"item\":\"https:\\\/\\\/ctp.rvltpreview.com\\\/portfolio\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Mixed-Use Portfolio\",\"item\":\"https:\\\/\\\/ctp.rvltpreview.com\\\/portfolio\\\/mixed-use\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Office Community\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ctp.rvltpreview.com\\\/#website\",\"url\":\"https:\\\/\\\/ctp.rvltpreview.com\\\/\",\"name\":\"Commercial Real Estate Developer And Manager\",\"description\":\"CTP - premium industrial warehouse and office buildings\",\"publisher\":{\"@id\":\"https:\\\/\\\/ctp.rvltpreview.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ctp.rvltpreview.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"sk-SK\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ctp.rvltpreview.com\\\/#organization\",\"name\":\"CTP\",\"url\":\"https:\\\/\\\/ctp.rvltpreview.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"sk-SK\",\"@id\":\"https:\\\/\\\/ctp.rvltpreview.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"CTP\"},\"image\":{\"@id\":\"https:\\\/\\\/ctp.rvltpreview.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>","yoast_head_json":{"title":"Kancel\u00e1rska komunita - developer a mana\u017e\u00e9r komer\u010dn\u00fdch nehnute\u013enost\u00ed","description":"Dlhodobo podporujeme vzdel\u00e1vanie mlad\u00fdch talentov a v r\u00e1mci CTParks podporujeme aj komunitn\u00fd rast.","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"sk_SK","og_type":"article","og_title":"Office Community","og_description":"We have been supporting the education of young talents for a long time, and within CTParks we also support community growth.","og_url":"https:\/\/ctp.rvltpreview.com\/sk\/portfolio\/mixed-use\/community\/","og_site_name":"Commercial Real Estate Developer And Manager","article_modified_time":"2023-11-02T11:58:33+00:00","og_image":[{"width":3000,"height":1246,"url":"https:\/\/ctp.rvltpreview.com\/wp-content\/uploads\/2020\/12\/ctp-community-web.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/ctp.rvltpreview.com\/portfolio\/mixed-use\/community\/","url":"https:\/\/ctp.rvltpreview.com\/portfolio\/mixed-use\/community\/","name":"Kancel\u00e1rska komunita - developer a mana\u017e\u00e9r komer\u010dn\u00fdch nehnute\u013enost\u00ed","isPartOf":{"@id":"https:\/\/ctp.rvltpreview.com\/#website"},"datePublished":"2020-11-25T09:50:32+00:00","dateModified":"2023-11-02T11:58:33+00:00","description":"Dlhodobo podporujeme vzdel\u00e1vanie mlad\u00fdch talentov a v r\u00e1mci CTParks podporujeme aj komunitn\u00fd rast.","breadcrumb":{"@id":"https:\/\/ctp.rvltpreview.com\/portfolio\/mixed-use\/community\/#breadcrumb"},"inLanguage":"sk-SK","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ctp.rvltpreview.com\/portfolio\/mixed-use\/community\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ctp.rvltpreview.com\/portfolio\/mixed-use\/community\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/ctp.rvltpreview.com\/cs\/"},{"@type":"ListItem","position":2,"name":"Portfolio","item":"https:\/\/ctp.rvltpreview.com\/portfolio\/"},{"@type":"ListItem","position":3,"name":"Mixed-Use Portfolio","item":"https:\/\/ctp.rvltpreview.com\/portfolio\/mixed-use\/"},{"@type":"ListItem","position":4,"name":"Office Community"}]},{"@type":"WebSite","@id":"https:\/\/ctp.rvltpreview.com\/#website","url":"https:\/\/ctp.rvltpreview.com\/","name":"Developer a mana\u017e\u00e9r komer\u010dn\u00fdch nehnute\u013enost\u00ed","description":"CTP - pr\u00e9miov\u00e9 priemyseln\u00e9 skladov\u00e9 a kancel\u00e1rske budovy","publisher":{"@id":"https:\/\/ctp.rvltpreview.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ctp.rvltpreview.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"sk-SK"},{"@type":"Organization","@id":"https:\/\/ctp.rvltpreview.com\/#organization","name":"CTP","url":"https:\/\/ctp.rvltpreview.com\/","logo":{"@type":"ImageObject","inLanguage":"sk-SK","@id":"https:\/\/ctp.rvltpreview.com\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"CTP"},"image":{"@id":"https:\/\/ctp.rvltpreview.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/ctp.rvltpreview.com\/sk\/wp-json\/wp\/v2\/pages\/11291","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ctp.rvltpreview.com\/sk\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/ctp.rvltpreview.com\/sk\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/ctp.rvltpreview.com\/sk\/wp-json\/wp\/v2\/users\/67"}],"replies":[{"embeddable":true,"href":"https:\/\/ctp.rvltpreview.com\/sk\/wp-json\/wp\/v2\/comments?post=11291"}],"version-history":[{"count":2,"href":"https:\/\/ctp.rvltpreview.com\/sk\/wp-json\/wp\/v2\/pages\/11291\/revisions"}],"predecessor-version":[{"id":89017,"href":"https:\/\/ctp.rvltpreview.com\/sk\/wp-json\/wp\/v2\/pages\/11291\/revisions\/89017"}],"up":[{"embeddable":true,"href":"https:\/\/ctp.rvltpreview.com\/sk\/wp-json\/wp\/v2\/pages\/72"}],"wp:attachment":[{"href":"https:\/\/ctp.rvltpreview.com\/sk\/wp-json\/wp\/v2\/media?parent=11291"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}